{"id":1952,"date":"2025-10-14T13:57:40","date_gmt":"2025-10-14T11:57:40","guid":{"rendered":"https:\/\/ontimesolutions.pl\/?p=1952"},"modified":"2025-11-11T14:11:44","modified_gmt":"2025-11-11T13:11:44","slug":"klasa-wykonania-konstrukcji-stalowej-jak-ja-dobrac-i-co-oznacza-dla-bezpieczenstwa-trwalosci-i-kosztow-inwestycji","status":"publish","type":"post","link":"https:\/\/ontimesolutions.pl\/de\/stahlbauklasse-wie-man-sie-wahlt-und-was-sie-fur-sicherheit-haltbarkeit-und-investitionskosten-bedeutet\/","title":{"rendered":"Stahlbauklasse - wie w\u00e4hlt man sie aus und was bedeutet sie f\u00fcr Sicherheit, Haltbarkeit und Investitionskosten?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1952\" class=\"elementor elementor-1952\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa0ae90 e-flex e-con-boxed e-con e-parent\" data-id=\"6aa0ae90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49957d6b elementor-widget elementor-widget-text-editor\" data-id=\"49957d6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p><strong>Klassen der Konstruktion<\/strong>definiert in <strong>Norm EN 1090<\/strong>sind ein Schl\u00fcsselelement im Entwurfs- und Bauprozess. Die richtige Wahl der EXC-Klasse ist nicht nur eine formale Anforderung, sondern hat einen realen Einfluss auf die Sicherheit von Mensch und Umwelt, die Zuverl\u00e4ssigkeit des Betriebs des Bauwerks sowie auf die <strong>Investitionskosten<\/strong> und ihre Funktionsweise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Was sind die EN 1090-Bauklassen?<\/strong><\/h2>\n\n\n\n<p><strong>Norm EN 1090-1 und EN 1090-2<\/strong> sind europ\u00e4ische Dokumente, die Regeln f\u00fcr Entwurf, Herstellung und Einbau von <strong>Stahl- und Aluminiumkonstruktionen<\/strong>. Als Teil dieser Gesetzgebung wurde die sogenannte <strong>EXC (Ausf\u00fchrungsklassen)<\/strong>die Strukturen nach folgenden Kriterien klassifizieren <strong>m\u00f6gliche Risiken<\/strong>der Schwierigkeitsgrad der Umsetzung und das erforderliche Ma\u00df an Kontrolle.<\/p>\n\n\n\n<p><strong>Bauklassen nach EN 1090<\/strong> umfassen vier Stufen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>EXC1<\/strong> - die einfachsten Konstruktionen mit geringem Nutzungsrisiko,<\/li>\n\n\n\n<li><strong>EXC2<\/strong> - typische Geb\u00e4udestrukturen,<\/li>\n\n\n\n<li><strong>EXC3<\/strong> - Bauwerke von hoher technologischer und gesellschaftlicher Bedeutung,<\/li>\n\n\n\n<li><strong>EXC4<\/strong> - die komplexesten, risikoreichsten <strong>Geb\u00e4ude<\/strong> i <strong>Ingenieurstrukturen<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Die Auswahl der richtigen Klasse sollte Teil einer fr\u00fchen <strong>Projekt<\/strong>unter Ber\u00fccksichtigung von <strong>l\u00e4dt<\/strong>der Ort der Anwendung und die Bedeutung des Objekts.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Was bedeutet die jeweilige EXC-Leistungsklasse?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>EXC-Klasse<\/strong><\/td><td><strong>Beschreibung der Konstruktion nach EN<\/strong><\/td><td><strong>Beispiele f\u00fcr die Verwendung<\/strong><\/td><td><strong>Anforderungen<\/strong><\/td><\/tr><tr><td><strong>EXC1<\/strong><\/td><td>Einfache Strukturen mit <strong>St\u00e4hle mit einer Festigkeitsklasse von bis zu 275 MPa<\/strong>haupts\u00e4chlich mit festen Lasten<\/td><td>Kleine landwirtschaftliche Hallen, Winterg\u00e4rten, <strong>Geb\u00e4ude mit bis zu zwei Stockwerken<\/strong><\/td><td>Einfache Kontrolle, vereinfachte Dokumentation<\/td><\/tr><tr><td><strong>EXC2<\/strong><\/td><td>Strukturen von mittlerer Komplexit\u00e4t, <strong>S700 Ausdauer<\/strong><\/td><td>Produktionshallen, <strong>Unterst\u00fctzungsstrukturen<\/strong>B\u00fcrogeb\u00e4ude<\/td><td>ZKP-Standardverfahren, Schwei\u00dfaufsicht, Einhaltung der Norm<\/td><\/tr><tr><td><strong>EXC3<\/strong><\/td><td>Dynamisch belastete oder besonders wichtige Strukturen<\/td><td><strong>Stra\u00dfen- und Eisenbahnbr\u00fccken<\/strong>Stadien, gro\u00dfe Industrieanlagen<\/td><td>Strenge Qualit\u00e4tskontrolle, Dokumentation nach <strong>EN 1090-2<\/strong>NDT-Pr\u00fcfungen<\/td><\/tr><tr><td><strong>EXC4<\/strong><\/td><td>Bauwerke mit der h\u00f6chsten Bedeutung und dem gr\u00f6\u00dften Gefahrenpotenzial<\/td><td>Kraftwerke, Hochh\u00e4user, milit\u00e4rische Einrichtungen<\/td><td>H\u00f6chste Anforderungen, vollst\u00e4ndige Dokumentation, \u00dcberwachung durch <strong>benannte Stelle<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Warum ist die EXC-Klasse so wichtig?<\/strong><\/h2>\n\n\n\n<p>Die Auswahl einer EXC-Klasse wirkt sich auf alle Elemente des Bauprozesses aus - von der Planung bis zur Ausf\u00fchrung und Abnahme. Klassen <strong>das Niveau der Qualit\u00e4tskontrolle zu bestimmen<\/strong>die Anforderungen f\u00fcr <strong>Schwei\u00dfen<\/strong>Materialpr\u00fcfung, technische Dokumentation und <strong>das System der werkseigenen Produktionskontrolle (FPC)<\/strong>.<\/p>\n\n\n\n<p>Eine fehlerhafte Klassenzuweisung kann zu Problemen f\u00fchren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>seri\u00f6s <strong>Ausf\u00e4lle<\/strong> oder Sch\u00e4den an der Struktur,<\/li>\n\n\n\n<li>Bedrohungen f\u00fcr <strong>das menschliche Leben und die Umwelt<\/strong>,<\/li>\n\n\n\n<li>Nichteinholung <strong>Konformit\u00e4tsbewertung<\/strong>,<\/li>\n\n\n\n<li>Ablehnung durch die Bauaufsicht.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Wie w\u00e4hlt man die richtige Leistungsklasse?<\/strong><\/h2>\n\n\n\n<p>Bei der Auswahl der Klasse sollte ber\u00fccksichtigt werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Komplexit\u00e4t und Funktion der Konstruktion<\/strong> - Je gr\u00f6\u00dfer das Risiko und die Bedeutung, desto h\u00f6her die Klasse.<\/li>\n\n\n\n<li><strong>Art der Lasten<\/strong> - ob sie nur statisch oder auch dynamisch sind (z. B. Vibrationen, St\u00f6\u00dfe).<\/li>\n\n\n\n<li><strong>Festigkeitsklasse von Stahl<\/strong> - EXC2 und h\u00f6her erfordern oft Stahlsorten <strong>S355 - S700<\/strong>.<\/li>\n\n\n\n<li><strong>Umwelt und Risikopotenzial<\/strong> - ob sich das Bauwerk an einem \u00f6ffentlichen Ort befindet oder aggressiven Bedingungen ausgesetzt ist.<\/li>\n<\/ul>\n\n\n\n<p><strong>Beispiel:<\/strong> F\u00fcr ein Standardlager reicht es oft aus, wenn <strong>EXC2-Klasse<\/strong>aber wenn es <strong>Industrieanlagen<\/strong> Vibrationen ausgesetzt sind, ist es sinnvoll, Folgendes zu ber\u00fccksichtigen <strong>EXC3<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Konstruktion von Stahl- und Aluminiumkonstruktionen gem\u00e4\u00df der Norm<\/strong><\/h2>\n\n\n\n<p>Jede <strong>Anlage<\/strong>der legal <strong>Stahl- oder Aluminiumkonstruktion nach EN 1090<\/strong>, muss:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einf\u00fchrung eines QC-Systems in \u00dcbereinstimmung mit <strong>EN ISO 3834<\/strong> i <strong>EN 1090-1<\/strong>,<\/li>\n\n\n\n<li>ein Zertifizierungsaudit bestehen durch <strong>benannte Stelle<\/strong>,<\/li>\n\n\n\n<li>\u00fcber dokumentierte Qualit\u00e4tskontrollverfahren verf\u00fcgen,<\/li>\n\n\n\n<li>die Einhaltung der Anforderungen zu gew\u00e4hrleisten <strong>EN 1090-2<\/strong> in Bezug auf die Leistung.<\/li>\n<\/ul>\n\n\n\n<p>Nur dann kann die Struktur die <strong>CE-Kennzeichnung<\/strong> und in der EU rechtlich zugelassen sein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bedeutung f\u00fcr den Investor - Sicherheit, Kosten und Nachhaltigkeit<\/strong><\/h2>\n\n\n\n<p>Die Auswahl einer EXC-Klasse ist nicht nur eine technische Angelegenheit - es ist eine Entscheidung, die sich direkt auf die <strong>Investitionskosten<\/strong>den Zeitplan und <strong>Betriebsrisiko<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Untere Klasse (z. B. EXC1)<\/strong> bedeutet einfachere Verfahren und geringere Kosten, aber begrenzte Gestaltungsm\u00f6glichkeiten.<\/li>\n\n\n\n<li><strong>H\u00f6here Klassen (EXC3 und EXC4)<\/strong> sind mit zus\u00e4tzlichen Kosten f\u00fcr Dokumentation, Pr\u00fcfung und \u00dcberwachung verbunden, bieten aber ein h\u00f6heres Niveau an <strong>Sicherheit, Nachhaltigkeit<\/strong> i <strong>Schadensresistenz<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>F\u00fcr viele industrielle Projekte, insbesondere solche, die der <strong>dynamischer Charakter der Arbeit<\/strong>, Klassenauswahl <strong>EXC3<\/strong> ist der Standard. F\u00fcr kritische Infrastrukturen - nur <strong>EXC4<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sie suchen das beste Stahlbauunternehmen? Z\u00e4hlen Sie auf ON-Time Solutions<\/strong><\/h2>\n\n\n\n<p>Wenn Sie Zuverl\u00e4ssigkeit, P\u00fcnktlichkeit und die Einhaltung von Normen w\u00fcnschen, vertrauen Sie Ihre <strong>Konstruktion von Stahlkonstruktionen durch ON-Time Solutions<\/strong>. Es handelt sich um einen erfahrenen Auftragnehmer, der die Investitionen gem\u00e4\u00df den Anforderungen der <strong>EN 1090<\/strong>und bietet einen umfassenden Service - vom Entwurf \u00fcber die Produktion bis zur Installation.&nbsp;<\/p>\n\n\n\n<p>ON-Time Solutions k\u00fcmmert sich um die richtige Auswahl von <strong>Leistungsklassen<\/strong>hohe Qualit\u00e4t <strong>Strukturelemente<\/strong> und volle Kompatibilit\u00e4t mit dem System <strong>ZKP<\/strong> und ISO-Normen. Mit ihnen wird Ihre Investition nicht nur sicher, sondern auch in Bezug auf Kosten und Nachhaltigkeit optimiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Zusammenfassung<\/strong><\/h2>\n\n\n\n<p>System <strong>Bauklassen nach EN 1090<\/strong> ist eine der wichtigsten S\u00e4ulen f\u00fcr Qualit\u00e4t und Sicherheit im Stahlbau. Die Auswahl der richtigen EXC-Klasse - von <strong>EXC1 bis EXC4<\/strong> - sollte eine bewusste Entscheidung des Planers und Bauherrn sein, die von der beabsichtigten Nutzung der Einrichtung, dem Grad des Risikos und der Erwartung an die Nachhaltigkeit abh\u00e4ngt.&nbsp;<\/p>\n\n\n\n<p><strong>Bau von Stahl- und Aluminiumkonstruktionen<\/strong> Die Einhaltung dieser Norm garantiert nicht nur die Legalit\u00e4t und die Erf\u00fcllung der formalen Anforderungen, sondern auch den tats\u00e4chlichen Schutz von Mensch und Umwelt vor den Auswirkungen m\u00f6glicher Fehler. Denken Sie daran: Die richtige Wahl der Leistungsklasse ist die Grundlage f\u00fcr eine solide Investition.<\/p>\n\n\n\n<p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caa6f95 elementor-widget elementor-widget-heading\" data-id=\"caa6f95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ - H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eccffe elementor-widget elementor-widget-n-accordion\" data-id=\"4eccffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Akkordeon. \u00d6ffnen Sie Links mit Enter oder Space, schlie\u00dfen Sie sie mit Escape und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8260\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-8260\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 1. Was bedeutet die EXC-Klassifizierung und wie viele Leistungsklassen gibt es? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8260\" class=\"elementor-element elementor-element-858df77 e-con-full e-flex e-con e-child\" data-id=\"858df77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0864e9 elementor-widget elementor-widget-heading\" data-id=\"f0864e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">In der Norm EN 1090 werden Bauwerke in vier Leistungsklassen eingeteilt: EXC1, EXC2, EXC3 und EXC4. Jede dieser Klassen legt Anforderungen an die Planung, Herstellung und Installation von Bauelementen fest, die von der Komplexit\u00e4t, dem Gef\u00e4hrdungspotenzial und der beabsichtigten Nutzung des Geb\u00e4udes abh\u00e4ngen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8261\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8261\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2. Welche Objekte sind in der Leistungsklasse EXC1 enthalten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8261\" class=\"elementor-element elementor-element-cc26d80 e-con-full e-flex e-con e-child\" data-id=\"cc26d80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8d0986 elementor-widget elementor-widget-heading\" data-id=\"a8d0986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Die EXC1-Ausf\u00fchrung umfasst Bauwerke von geringer sicherheitstechnischer Bedeutung, wie z. B. landwirtschaftliche Geb\u00e4ude, Schuppen oder Winterg\u00e4rten. Diese Bauwerke oder Tragwerke sind haupts\u00e4chlich st\u00e4ndigen Lasten ausgesetzt, bestehen aus Stahl mit einer Festigkeitsklasse von bis zu 275 MPa und haben vereinfachte Konstruktions- und Pr\u00fcfanforderungen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8262\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8262\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 3. Wie kann man ein Geb\u00e4ude der richtigen Leistungsklasse zuordnen? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8262\" class=\"elementor-element elementor-element-12dd10b e-con-full e-flex e-con e-child\" data-id=\"12dd10b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f58bb5 elementor-widget elementor-widget-heading\" data-id=\"6f58bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Die Einstufung von Bauwerken in bestimmte Leistungsklassen h\u00e4ngt von Faktoren wie der Art des Geb\u00e4udes, seiner Funktion, der H\u00f6he der Belastung, der sozialen oder technischen Bedeutung und der Materialspezifikation ab. Die Wahl der Klasse wird vom Planer in \u00dcbereinstimmung mit den Leitlinien der EN 1090-2 und einer Risikoanalyse getroffen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8263\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8263\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 4. M\u00fcssen alle Teile der Struktur die gleiche EXC-Klasse haben? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8263\" class=\"elementor-element elementor-element-39534dd e-flex e-con-boxed e-con e-child\" data-id=\"39534dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-512bb0a elementor-widget elementor-widget-heading\" data-id=\"512bb0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Nein, es ist m\u00f6glich, verschiedenen Teilen eines Bauwerks unterschiedliche Klassen zuzuordnen. Zum Beispiel k\u00f6nnen Haupttragwerke oder tragende Strukturen die Klasse EXC3 erfordern, w\u00e4hrend Hilfselemente nur nach EXC2 ausgelegt werden m\u00fcssen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8264\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8264\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 5 Wer legt die Richtlinien f\u00fcr die EXC-Klasse fest? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8264\" class=\"elementor-element elementor-element-5329ea1 e-flex e-con-boxed e-con e-child\" data-id=\"5329ea1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07959bd elementor-widget elementor-widget-heading\" data-id=\"07959bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Die Richtlinien f\u00fcr die EXC-Klassen sind in EN 1090-2 enthalten, und ihre Anwendung wird von einer benannten Stelle im Rahmen des Konformit\u00e4tsbewertungssystems \u00fcberwacht. Planer, Ingenieure und Bauunternehmer m\u00fcssen diese Anforderungen in jeder Phase des Projekts ber\u00fccksichtigen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8265\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8265\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 6. haben die Leistungsklassen einen Einfluss auf die Investitionskosten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8265\" class=\"elementor-element elementor-element-6e00fbd e-flex e-con-boxed e-con e-child\" data-id=\"6e00fbd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d64eb0a elementor-widget elementor-widget-heading\" data-id=\"d64eb0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Ja. Je h\u00f6her die Leistungsklasse, desto strenger sind die Anforderungen an die Dokumentation, die Materialien und die Pr\u00fcfung, was sich in h\u00f6heren Konstruktions- und Herstellungskosten niederschl\u00e4gt. Daher sollte jede Baugruppe je nach tats\u00e4chlichem Risiko in die entsprechende Klasse eingestuft werden.\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"1. Co oznacza klasyfikacja EXC i ile jest klas wykonania?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Norma PN-EN 1090 dzieli konstrukcje na cztery klasy wykonania: EXC1, EXC2, EXC3 i EXC4. Ka\\u017cda z nich okre\\u015bla wymagania dla projektowania, produkcji i monta\\u017cu element\\u00f3w konstrukcyjnych, w zale\\u017cno\\u015bci od stopnia z\\u0142o\\u017cono\\u015bci, potencjalnego zagro\\u017cenia i przeznaczenia obiektu.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"2. Jakie obiekty zaliczaj\\u0105 si\\u0119 do klasy wykonania EXC1?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Do wykonania EXC1 zalicza si\\u0119 elementy konstrukcyjne o niewielkim znaczeniu dla bezpiecze\\u0144stwa, jak np. budynki rolnicze, wiaty czy ogrody zimowe. Te konstrukcje lub konstrukcje no\\u015bne s\\u0105 poddawane g\\u0142\\u00f3wnie sta\\u0142ym obci\\u0105\\u017ceniom, wykonane ze stali o klasie wytrzyma\\u0142o\\u015bci do 275 MPa i maj\\u0105 uproszczone wymagania projektowe i kontrolne.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"3. Jak przypisa\\u0107 budynek do odpowiedniej klasy wykonania?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Podzia\\u0142 budowli do poszczeg\\u00f3lnych klas wykonania zale\\u017cy od takich czynnik\\u00f3w jak: typ obiektu, jego funkcja, poziom obci\\u0105\\u017cenia, znaczenie spo\\u0142eczne lub technologiczne oraz specyfikacja materia\\u0142\\u00f3w. Doboru klasy dokonuje projektant, zgodnie z wytycznymi normy PN-EN 1090-2 oraz analiz\\u0105 ryzyka.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"4. Czy ka\\u017cda cz\\u0119\\u015b\\u0107 konstrukcji musi mie\\u0107 tak\\u0105 sam\\u0105 klas\\u0119 EXC?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Nie, mo\\u017cliwe jest przypisanie r\\u00f3\\u017cnych klas do poszczeg\\u00f3lnych cz\\u0119\\u015bci konstrukcji. Na przyk\\u0142ad \\u2013 g\\u0142\\u00f3wne elementy konstrukcyjne lub konstrukcje no\\u015bne mog\\u0105 wymaga\\u0107 klasy EXC3, podczas gdy pomocnicze elementy wystarczy zaprojektowa\\u0107 wg EXC2.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"5. Kto ustala wytyczne dla klasy EXC?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Wytyczne dotycz\\u0105ce klas EXC s\\u0105 zawarte w normie PN-EN 1090-2, a ich stosowanie nadzoruje jednostka notyfikowana w ramach systemu oceny zgodno\\u015bci. Projektanci, in\\u017cynierowie i wykonawcy musz\\u0105 uwzgl\\u0119dni\\u0107 te wymagania na ka\\u017cdym etapie realizacji inwestycji.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"6. Czy klasy wykonania maj\\u0105 wp\\u0142yw na koszty inwestycji?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Tak. Im wy\\u017csza klasa wykonania, tym bardziej rygorystyczne wymagania wobec dokumentacji, materia\\u0142\\u00f3w i kontroli, co przek\\u0142ada si\\u0119 na wi\\u0119ksze koszty projektowe i produkcyjne. Dlatego ka\\u017cda grupa konstrukcji powinna by\\u0107 przypisana do odpowiedniej klasy zgodnie z rzeczywistym poziomem ryzyka.\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Ausf\u00fchrungsklassen von Tragwerken, wie in der Norm PN-EN 1090 definiert, sind ein entscheidendes Element des Planungs- und Ausf\u00fchrungsprozesses. Die richtige Wahl der EXC-Klasse ist nicht nur eine formale Anforderung, sondern eine reale Auswirkung auf die Sicherheit von Mensch und Umwelt, die Zuverl\u00e4ssigkeit des Tragwerks sowie die Kosten der Investition und ihres Betriebs. Was sind Ausf\u00fchrungsklassen von Tragwerken gem\u00e4\u00df PN-EN 1090? Die Norm PN-EN 1090-1 und PN-EN [\u2026]<\/p>","protected":false},"author":1,"featured_media":1953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":4,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"predecessor-version":[{"id":1958,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/posts\/1952\/revisions\/1958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/media\/1953"}],"wp:attachment":[{"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ontimesolutions.pl\/de\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}